{"id":1159,"date":"2024-06-25T16:13:32","date_gmt":"2024-06-25T23:13:32","guid":{"rendered":"https:\/\/artefactonoticias.com\/?p=1159"},"modified":"2024-06-25T16:13:34","modified_gmt":"2024-06-25T23:13:34","slug":"aprueban-reforma-a-ley-de-la-comision-de-arbitraje-medico-del-estado","status":"publish","type":"post","link":"https:\/\/artefactonoticias.com\/index.php\/2024\/06\/25\/aprueban-reforma-a-ley-de-la-comision-de-arbitraje-medico-del-estado\/","title":{"rendered":"APRUEBAN REFORMA A LEY DE LA COMISI\u00d3N DE ARBITRAJE M\u00c9DICO DEL ESTADO"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223328-768x1024.jpg\" alt=\"\" class=\"wp-image-1160\" srcset=\"https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223328-768x1024.jpg 768w, https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223328-225x300.jpg 225w, https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223328.jpg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Secretario T\u00e9cnico del CAME podr\u00e1 postular peritos al Comit\u00e9 Consultivo en ausencia de \u00f3rgano colegiado especializado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Adem\u00e1s, se incorpora el lenguaje incluyente y se actualizan los nombres de las dependencias estatales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mexicali, B. C., domingo 23 de junio de 2024.- Con la intenci\u00f3n de facultar al Secretario T\u00e9cnico de la Comisi\u00f3n de Arbitraje M\u00e9dico (CAME), para que postule integrantes al Comit\u00e9 Consultivo de Peritos, cuando no exista un \u00f3rgano colegiado integrado en alguna \u00e1rea m\u00e9dica especializada, la XXIV Legislatura aprob\u00f3 la iniciativa de reforma presentada por la diputada Mar\u00eda Monserrat Rodr\u00edguez Lorenzo.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"1161\" src=\"https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223328-1-768x1024.jpg\" alt=\"\" class=\"wp-image-1161\" srcset=\"https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223328-1-768x1024.jpg 768w, https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223328-1-225x300.jpg 225w, https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223328-1.jpg 960w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n\n\n\n<pre class=\"wp-block-code\"><code>La CAME tiene dentro de sus principales atribuciones las de: asesorar a los usuarios sobre sus derechos, investigar y atender quejas, conciliar conflictos en la prestaci\u00f3n de servicios de salud, actuar como \u00e1rbitro y emitir laudos, opiniones t\u00e9cnicas sobre quejas, notificar a las autoridades y organismos profesionales sobre la negativa de los prestadores a proporcionar informaci\u00f3n solicitada, etc\u00e9tera.\n\nMonserrat Rodr\u00edguez explic\u00f3 que, para cumplir con dichas responsabilidades, la Comisi\u00f3n de Arbitraje cuenta con un Comit\u00e9 Consultivo de Peritos, definido por la ley como un cuerpo colegiado de especialistas en diversas \u00e1reas de la salud, cuya principal funci\u00f3n es la de emitir opiniones t\u00e9cnicas y dict\u00e1menes.\n\n\u201cSin embargo, en ocasiones se torna dif\u00edcil la integraci\u00f3n de este Comit\u00e9, ante la ausencia de asociaciones o colegios de profesionistas en determinada especialidad de salud, debidamente registrados en la entidad\u201d, apunt\u00f3.\n\nPor esta raz\u00f3n la legisladora consider\u00f3 necesario prever en la ley, que en caso de que no exista asociaci\u00f3n o colegio en una rama espec\u00edfica de salud, corresponder\u00e1 al Secretario T\u00e9cnico de la CAME realizar la propuesta respectiva, a fin de que la Junta Directiva este en condiciones de aprobar e integrar el Comit\u00e9 para cada caso en espec\u00edfico.\n\nDe esta manera, se permitir\u00e1 que en todos los casos en que se presenten quejas relacionadas con la prestaci\u00f3n de servicios de atenci\u00f3n a la salud, se integre el Comit\u00e9 para opinar o dictaminar lo conducente.\n\n Esta iniciativa tambi\u00e9n consider\u00f3 actualizar las denominaciones del Estado con base a la Ley Org\u00e1nica del Poder Ejecutivo y la incorporaci\u00f3n de lenguaje incluyente, todo esto en la Ley de la Comisi\u00f3n de Arbitraje M\u00e9dico del Estado de Baja California, en sus art\u00edculos 3, del 8 al 25, 29, 33, 34, 36, 42, 50, 52, 53, 54, 60, 63, 64, 65, 67, 72, 75, 76, 78, 84 y 86.<\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Secretario T\u00e9cnico del CAME podr\u00e1 postular peritos al Comit\u00e9 Consultivo en ausencia de \u00f3rgano&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1159","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/1159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=1159"}],"version-history":[{"count":1,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/1159\/revisions"}],"predecessor-version":[{"id":1162,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/1159\/revisions\/1162"}],"wp:attachment":[{"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=1159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=1159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=1159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}