{"id":1151,"date":"2024-06-25T14:12:31","date_gmt":"2024-06-25T21:12:31","guid":{"rendered":"https:\/\/artefactonoticias.com\/?p=1151"},"modified":"2024-06-25T14:12:33","modified_gmt":"2024-06-25T21:12:33","slug":"propone-dip-carolina-rivas-que-se-atienda-problematica-de-transporte-escolar-de-puerta-trampa","status":"publish","type":"post","link":"https:\/\/artefactonoticias.com\/index.php\/2024\/06\/25\/propone-dip-carolina-rivas-que-se-atienda-problematica-de-transporte-escolar-de-puerta-trampa\/","title":{"rendered":"PROPONE DIP. CAROLINA RIVAS QUE SE ATIENDA PROBLEM\u00c1TICA DE TRANSPORTE ESCOLAR DE PUERTA TRAMPA"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"960\" src=\"https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223300.jpg\" alt=\"\" class=\"wp-image-1152\" srcset=\"https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223300.jpg 768w, https:\/\/artefactonoticias.com\/wp-content\/uploads\/2024\/06\/1000223300-240x300.jpg 240w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Exhorta a las distintas autoridades que intervienen en esta problem\u00e1tica para activar un Plan de Trabajo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2022 Los estudiantes de educaci\u00f3n b\u00e1sica y media deben trasladarse casi 7 kil\u00f3metros a pie en condiciones climatol\u00f3gicas extremas de calor y fr\u00edo, a la Delegaci\u00f3n Real del Castillo de Ensenada<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mexicali, B.C., lunes 24 de junio de 2024.- \u201cEstoy convencida de que, uniendo fuerzas, podremos garantizar que ning\u00fan ni\u00f1o o ni\u00f1a se quede atr\u00e1s, por falta de oportunidades educativas y juntos podemos crear un entorno donde cada mente brillante encuentre su lugar y su voz\u201d, indic\u00f3 la diputada Carolina Rivas Garc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es el tiempo de que se reafirme el compromiso por una educaci\u00f3n inclusiva, accesible y de calidad para todos, demostrando con nuestros actos que las distancias no deben ser un obst\u00e1culo insuperable cuando se trata de brindar conocimiento y esperanza a las generaciones venideras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La legisladora mencion\u00f3 que las distancias f\u00edsicas y sociales separan a muchos de nuestros j\u00f3venes, del conocimiento que necesitan. Y desde las regiones m\u00e1s apartadas hasta nuestras ciudades, existen desaf\u00edos significativos que limitan el acceso equitativo a la educaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello -dijo- debemos trabajar juntos para derribar las barreras geogr\u00e1ficas y socioecon\u00f3micas que impiden a tantos, alcanzar su m\u00e1ximo potencial educativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, hizo un llamado a las distintas autoridades que intervienen en esta problem\u00e1tica para activar un Plan de Trabajo que d\u00e9 soluci\u00f3n a los estudiantes de educaci\u00f3n b\u00e1sica y media de la comunidad de Puerta Trampa que deben trasladarse casi 7 kil\u00f3metros a pie en condiciones climatol\u00f3gicas extremas de calor y fr\u00edo a la Delegaci\u00f3n Real del Castillo de Ensenada, para tomar sus actividades acad\u00e9micas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para tales fines, exhort\u00f3 a la gobernadora de Baja California, a efecto de que, por conducto del titular de la Secretar\u00eda de Educaci\u00f3n, y\/o en conjunto con el Instituto de Movilidad Sustentable del Estado, se instale una mesa de trabajo que pueda dar soluci\u00f3n a la necesidad de transporte escolar de la citada comunidad ensenadense.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carolina Rivas enfatiz\u00f3 en que: \u201cnecesitamos actuar ahora, con determinaci\u00f3n y solidaridad, para construir un futuro donde todas y todos puedan aprender, crecer y contribuir plenamente a nuestra sociedad\u201d. Esto debido a que, cuando un ni\u00f1o o una ni\u00f1a recibe una educaci\u00f3n adecuada, no solo se enriquece su mundo personal, sino que se abre una puerta a oportunidades que transforman vidas enteras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presente exhorto fue aprobado por el Pleno con dispensa de tr\u00e1mite, por la mayor\u00eda de las diputadas y diputados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Exhorta a las distintas autoridades que intervienen en esta problem\u00e1tica para activar un Plan&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1151","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=1151"}],"version-history":[{"count":1,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/1151\/revisions"}],"predecessor-version":[{"id":1153,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/1151\/revisions\/1153"}],"wp:attachment":[{"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=1151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=1151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/artefactonoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}